{"id":7632,"date":"2019-05-20T07:06:20","date_gmt":"2019-05-20T05:06:20","guid":{"rendered":"https:\/\/www.ghcranes.com\/blog\/?p=7632"},"modified":"2019-05-13T17:06:40","modified_gmt":"2019-05-13T15:06:40","slug":"la-eleccion-un-viaje-mas-alla-de-la-realidad","status":"publish","type":"post","link":"https:\/\/www.ghcranes.com\/blog\/la-eleccion-un-viaje-mas-alla-de-la-realidad\/","title":{"rendered":"LA ELECCI\u00d3N: UN VIAJE MAS ALL\u00c1 DE LA REALIDAD"},"content":{"rendered":"<h3>Nuestra visi\u00f3n de la empresa va m\u00e1s all\u00e1 de lo que nos muestra la propia realidad.<\/h3>\n<p>Para entender el futuro, hace unos a\u00f1os contratamos a George Hans Bridge (GHB) como \u201cobservador internacional\u201d.<\/p>\n<p>\u00c9l tiene vida en un c\u00f3mic que nos anuncia y nos describe el futuro. Le contratamos porque representa muchos de los valores de GH: Es un hombre preparado, universal, audaz, valiente y con capacidad para entender el mundo.<\/p>\n<p>Es un moderno gentleman ingl\u00e9s que ahora nos ayuda a interpretar el futuro.<\/p>\n<p>Aqu\u00ed nos explica como fue capaz de convencer a Mr. Lee de que GH es una apuesta ganadora<br \/>\n\u00bfFicci\u00f3n?, \u00bfrealidad? Juzguen ustedes mismos.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/WTyq7STxj2I\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nuestra visi\u00f3n de la empresa va m\u00e1s all\u00e1 de lo que nos muestra la propia realidad. Para entender el futuro, hace unos a\u00f1os contratamos a George Hans Bridge (GHB) como \u201cobservador internacional\u201d. \u00c9l tiene vida en un c\u00f3mic que nos anuncia y nos describe el futuro. Le contratamos porque representa muchos de los valores de [&hellip;]<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":7634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[1200,1199,1202,1201,85,971,184],"jetpack_featured_media_url":"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2019\/05\/El-Universo-de-George-H.B.-Reencuentro-en-Singapur.jpg","_links":{"self":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/7632"}],"collection":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/comments?post=7632"}],"version-history":[{"count":7,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/7632\/revisions"}],"predecessor-version":[{"id":7645,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/7632\/revisions\/7645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/media\/7634"}],"wp:attachment":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/media?parent=7632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/categories?post=7632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/tags?post=7632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}