{"id":2648,"date":"2016-01-28T08:30:55","date_gmt":"2016-01-28T07:30:55","guid":{"rendered":""},"modified":"2016-01-27T19:15:59","modified_gmt":"2016-01-27T18:15:59","slug":"fcc-presa-de-castrovido","status":"publish","type":"post","link":"https:\/\/www.ghcranes.com\/blog\/fcc-presa-de-castrovido\/","title":{"rendered":"FCC (Presa de Castrovido)"},"content":{"rendered":"<p>Espectacular montaje de <strong>3 puentes gr\u00faa birrailes GH (2 de 8 Tn y 1 de 10 Tn)<\/strong>, instalados en las c\u00e1maras de v\u00e1lvulas de emblem\u00e1tica la <strong>presa de Castrovido<\/strong> (Terrazas \u2013 Burgos). La obra est\u00e1 siendo acometida por <strong>FCC<\/strong>, y se trata de una de las mayores obras del Plan Hidrol\u00f3gico Nacional, tanto por a\u00f1os de ejecuci\u00f3n, como por importe de la inversi\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-1.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-2703\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-1.jpg\" alt=\"FCC (Presa Castrovido) (1)\" width=\"604\" height=\"402\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-1.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-1-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-1-624x416.jpg 624w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/a><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-2.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-2704\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-2-300x200.jpg\" alt=\"FCC (Presa Castrovido) (2)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-2-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-2.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-2-624x416.jpg 624w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-3.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-2705\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-3-300x200.jpg\" alt=\"FCC (Presa Castrovido) (3)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-3-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-3.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-3-624x416.jpg 624w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La particularidad de la operaci\u00f3n, ha venido motivada por un inusual sistema de traslado de las gr\u00faas hasta su ubicaci\u00f3n final, en las c\u00e1maras de v\u00e1lvulas.<\/p>\n<p><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-7.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-2707\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-7-300x200.jpg\" alt=\"FCC (Presa Castrovido) (7)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-7-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-7.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-7-624x416.jpg 624w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-11.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-2706\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-11-300x200.jpg\" alt=\"FCC (Presa Castrovido) (11)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-11-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-11.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-11-624x416.jpg 624w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Las c\u00e1maras est\u00e1n en distintos puntos del muro de la presa, y a distintas alturas, de ah\u00ed que los montajes se hayan tenido que ir acometiendo en distintos momentos, a medida que la obra ha ido avanzando.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-10.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-2708\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-10.jpg\" alt=\"FCC (Presa Castrovido) (10)\" width=\"381\" height=\"768\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-10.jpg 381w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-10-149x300.jpg 149w\" sizes=\"(max-width: 381px) 100vw, 381px\" \/><\/a><\/p>\n<p>Una vez llega la construcci\u00f3n del muro a la altura del suelo de la c\u00e1mara, siguen levantando las paredes laterales hasta la altura de las m\u00e9nsulas. Llegados a este punto, es cuando se procede a instalar la gr\u00faa. Desde tierra firme (lateral del muro de la presa), se suspende el puente gr\u00faa con la gr\u00faa blondin y se desplaza por el cable como si fuera una tirolina de <strong>746 mts de longitud, a una velocidad de traslaci\u00f3n de 420 m.p.m. y 150 m.p.m. de velocidad de elevaci\u00f3n \/ descenso<\/strong>, introduci\u00e9ndola por la parte superior de la c\u00e1mara. Cabe destacar tambi\u00e9n, que <strong>los puentes gr\u00faa ha viajado a unos 100 mts de altura del suelo, <\/strong>por lo que el nivel de seguridad era m\u00e1ximo.<\/p>\n<p><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-12.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-2710\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-12.jpg\" alt=\"FCC (Presa Castrovido) (12)\" width=\"300\" height=\"450\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-12.jpg 512w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-12-200x300.jpg 200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-14.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-2709\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-14.jpg\" alt=\"FCC (Presa de Castrovido) (14)\" width=\"300\" height=\"450\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-14.jpg 512w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-14-200x300.jpg 200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-15.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-2712\" src=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-15.jpg\" alt=\"FCC (Presa de Castrovido) (15)\" width=\"604\" height=\"402\" srcset=\"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-15.jpg 1024w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-15-300x200.jpg 300w, https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-de-Castrovido-15-624x416.jpg 624w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p>Tras el montaje de la gr\u00faa, siguen hormigonando y cerrando la c\u00e1mara con forma redonda de b\u00f3veda. Una vez se cierra la b\u00f3veda, ya no es posible meter ni sacar elementos voluminosos, porque \u00fanicamente quedar\u00e1n galer\u00edas de paso para personas y peque\u00f1os veh\u00edculos, de cara a \u00a0facilitar su acceso cuando haya que realizar labores de mtto.<\/p>\n<p><em>GH sigue estando presente, en las principales obras de infraestructuras de Obras P\u00fablicas.<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Espectacular montaje de 3 puentes gr\u00faa birrailes GH (2 de 8 Tn y 1 de 10 Tn), instalados en las c\u00e1maras de v\u00e1lvulas de emblem\u00e1tica la presa de Castrovido (Terrazas \u2013 Burgos). La obra est\u00e1 siendo acometida por FCC, y se trata de una de las mayores obras del Plan Hidrol\u00f3gico Nacional, tanto por a\u00f1os [&hellip;]<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":2702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[243,582,49,544,584,583,581],"jetpack_featured_media_url":"https:\/\/www.ghcranes.com\/blog\/wp-content\/uploads\/2016\/01\/FCC-Presa-Castrovido-0-e1453902762165.jpg","_links":{"self":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/2648"}],"collection":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/comments?post=2648"}],"version-history":[{"count":4,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/2648\/revisions"}],"predecessor-version":[{"id":2713,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/posts\/2648\/revisions\/2713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/media\/2702"}],"wp:attachment":[{"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/media?parent=2648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/categories?post=2648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ghcranes.com\/blog\/wp-json\/wp\/v2\/tags?post=2648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}